{"id":1,"date":"2013-05-15T00:56:26","date_gmt":"2013-05-14T22:56:26","guid":{"rendered":"http:\/\/www.schwierenstein.de\/schwieren2\/?p=1"},"modified":"2017-03-27T19:08:43","modified_gmt":"2017-03-27T17:08:43","slug":"restaurierung-sankt-mauritius-koeln","status":"publish","type":"post","link":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/restaurierung-sankt-mauritius-koeln\/","title":{"rendered":"Restaurierung Sankt-Mauritius K\u00f6ln"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16536 alignright\" src=\"http:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2-300x200.jpg 300w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2-600x400.jpg 600w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2-768x512.jpg 768w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2-1024x683.jpg 1024w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3083-2.jpg 1417w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><strong>Kirche St. Mauritius:<\/strong> Die Pfarrkirche St. Mauritius in K\u00f6ln wurde erstmals im Jahr\u00a01135 erw\u00e4hnt. Das Bauwerk steht auf dem nach ihm benannten Mauritiuskirchplatz im Stadtteil Altstadt-S\u00fcd. In den folgenden Jahrhunderten hat sich das Erscheinungsbild der Kirche durch Umbauten, Abtragungen und Erneuerungen vielfach ver\u00e4ndert.<\/p>\n<p>Die Grundsteinlegung des heutigen Baus \u2013 der neugotischen Kirche \u2013 erfolgte im Jahr 1861. Es entstand eine dreischiffige Basilika, nach Vorbild der Trierer Liebfrauenkirche. Die Einweihung fand Mitte 1865 statt, die Fertigstellung erfolgte jedoch erst Ende 1866. Nach Kriegsende 1945 standen nur noch Teile der Au\u00dfenmauern und der Turm der Kirche. Erst im Jahr 1956 wurde mit der Errichtung eines jetzt kleineren Kirchenbaues begonnen.<\/p>\n<p><strong>Turm und Portal:<\/strong> Auf dem Turm steht eine etwa 3,50m hohe Figur, die den Schutzpatron der Kirche, den heiligen Mauritius, darstellt. Diese wurde vom Dombildhauer Peter Fuchs (1829\u201389) gehauen.<\/p>\n<p><strong>Die Firma Schwieren Steinmetzwerkst\u00e4tten wurde mit der Durchf\u00fchrung folgender Restaurierungs- und Sanierungsarbeiten beauftrag: <\/strong>Maurer- und Verfugarbeiten Turmhelm, Turmschaft und Hauptschiff, Natursteinarbeiten Turmhelm und Turmschaft und Sanierputzarbeiten im Kircheninnenraum.<\/p>\n<p>Hierzu geh\u00f6rte das Aufschneiden der vorhandenen schadhaften Fugen am Natursteinmauerwerk und vollfl\u00e4chiges Verfugen mit gepr\u00fcfter M\u00f6rtelrezeptur. Das Ausstemmen von kaputten Ziegelsteinfl\u00e4chen inklusive Lieferung und Beimauerung. Die Reinigung der Mauerwerksfl\u00e4chen mittels Niederdruckrotationsverfahren. Die Aufarbeitung der vorhandenen Strebeb\u00f6gen inklusive Neuverfugung, Nachbehandlung und Reinigung. Das Ausstemmen, Demontieren und Reinigen vorhandener profilierter Werksteine inklusive Anfertigung und Lieferung neuer Werksteine sowie das Neuversetzen der Werksteine. Die Lieferung und der Austausch von besch\u00e4digten Natursteinelementen in Basaltlava inklusive der Verankerung in V4a Edelstahl.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-16528 alignleft\" src=\"http:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3114-b-300x200.jpg\" alt=\"Bekr\u00f6nungsfigur St. Mauritius\" width=\"248\" height=\"165\" srcset=\"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3114-b-300x200.jpg 300w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3114-b-600x400.jpg 600w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3114-b-768x512.jpg 768w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2017\/03\/IMG_3114-b.jpg 850w\" sizes=\"(max-width: 248px) 100vw, 248px\" \/>Besondere Anspr\u00fcche stellte die Sanierung der vorhandenen Bekr\u00f6nungsskulptur in 72 Metern H\u00f6he. Diese wurde demontiert, gereinigt, aufgearbeitet und erg\u00e4nzt. Bei der Neumontage der Bekr\u00f6nungsfigur wurden alle Einzelteile mit V4A Verankerungen verankert und alle Au\u00dfenfugen mit ged\u00fcster Bleiwolle verf\u00fcllt.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16539 alignright\" src=\"http:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b-300x157.jpg\" alt=\"\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b-300x157.jpg 300w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b-600x315.jpg 600w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b-768x403.jpg 768w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b-1024x537.jpg 1024w, https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-content\/uploads\/2013\/05\/St-Mauritius-K\u00f6ln-Innenraum-b.jpg 1281w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Dar\u00fcber hinaus wurden Sanierputzarbeiten im Kircheninnenraum durchgef\u00fchrt. Hierzu geh\u00f6rte das Entfernen des schadhaften Innenputzes und die fachgerechte Reinigung der Mauerwerksfl\u00e4chen. Anschlie\u00dfend wurden die Mauerwerksfl\u00e4chen mit einem Sanierungsspritzbewurf fachgerecht vorbehandelt und mit einem Sanierungsputz und anschlie\u00dfend Sanierfeinputz vollfl\u00e4chig verputzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kirche St. Mauritius: Die Pfarrkirche St. Mauritius in K\u00f6ln wurde erstmals im Jahr\u00a01135 erw\u00e4hnt. Das Bauwerk steht auf dem nach ihm benannten Mauritiuskirchplatz im Stadtteil Altstadt-S\u00fcd. In den folgenden Jahrhunderten hat sich das Erscheinungsbild der Kirche durch Umbauten, Abtragungen und Erneuerungen vielfach ver\u00e4ndert. Die Grundsteinlegung des heutigen Baus \u2013 der neugotischen Kirche \u2013 erfolgte im Jahr 1861. Es entstand eine dreischiffige Basilika, nach Vorbild der Trierer Liebfrauenkirche. Die Einweihung fand Mitte 1865 statt, die Fertigstellung erfolgte jedoch erst Ende 1866. Nach Kriegsende 1945 standen nur noch Teile der Au\u00dfenmauern und der Turm der Kirche. Erst im Jahr 1956 wurde mit der Errichtung eines jetzt kleineren Kirchenbaues begonnen. Turm und Portal: Auf dem Turm steht eine etwa 3,50m hohe Figur, die den Schutzpatron der Kirche, den heiligen Mauritius, darstellt. Diese wurde vom Dombildhauer Peter Fuchs (1829\u201389) gehauen. Die Firma Schwieren Steinmetzwerkst\u00e4tten wurde mit der Durchf\u00fchrung folgender Restaurierungs- und Sanierungsarbeiten beauftrag: Maurer- und Verfugarbeiten Turmhelm, Turmschaft und Hauptschiff, Natursteinarbeiten Turmhelm und Turmschaft und Sanierputzarbeiten im Kircheninnenraum. Hierzu geh\u00f6rte das Aufschneiden der vorhandenen schadhaften Fugen am Natursteinmauerwerk und vollfl\u00e4chiges Verfugen mit gepr\u00fcfter M\u00f6rtelrezeptur. Das Ausstemmen von kaputten Ziegelsteinfl\u00e4chen inklusive Lieferung und Beimauerung. Die Reinigung der Mauerwerksfl\u00e4chen mittels Niederdruckrotationsverfahren. Die Aufarbeitung der vorhandenen Strebeb\u00f6gen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[68,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":12,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":16546,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/posts\/1\/revisions\/16546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/media\/16528"}],"wp:attachment":[{"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwierenstein.de\/steinmetzwerkstaetten\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}